{"id":32554,"date":"2024-08-28T14:19:15","date_gmt":"2024-08-28T12:19:15","guid":{"rendered":"https:\/\/numeractive.ch\/?page_id=32554"},"modified":"2024-08-28T15:34:55","modified_gmt":"2024-08-28T13:34:55","slug":"augmentez-votre-notoriete-et-votre-credibilite","status":"publish","type":"page","link":"https:\/\/numeractive.ch\/it\/","title":{"rendered":"Aumenta la tua notoriet\u00e0 e credibilit\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32554\" class=\"elementor elementor-32554\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7346e0a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7346e0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13b5dcc\" data-id=\"13b5dcc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48821b2 elementor-widget elementor-widget-linoor-main-slider\" data-id=\"48821b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-main-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        \r\n            <!-- Banner Section -->\r\n            <section class=\"banner-section banner-two\">\r\n                                <div class=\"banner-carousel owl-theme owl-carousel\">\r\n                                            <!-- Slide Item -->\r\n                        <div class=\"slide-item\">\r\n                            <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/gabriel-varaljay-Lap5tXHLsYg-unsplash-scaled.jpg);\"><\/div>\r\n                            <div class=\"shape-1\"><\/div>\r\n                            <div class=\"shape-2\"><\/div>\r\n                            <div class=\"shape-3\"><\/div>\r\n                            <div class=\"shape-4\"><\/div>\r\n                            <div class=\"shape-5\"><\/div>\r\n                            <div class=\"shape-6\"><\/div>\r\n                            <div class=\"auto-container\">\r\n                                <div class=\"content-box\">\r\n                                    <div class=\"content\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"sub-title\">Fini les t\u00e9l\u00e9phones inutiles, place \u00e0 l'automatisation LinkedIn!<\/div>\r\n                                            <h1>Automatisez votre prospection avec LinkedIn<\/h1>\r\n                                            <div class=\"link-box\">\r\n                                                <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/service\/prospection-linkedin\/\">\r\n                                                    <i class=\"btn-curve\"><\/i>\r\n                                                    <span class=\"btn-title\">D\u00e9marchez des entreprises<\/span>\r\n                                                <\/a>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <!-- Slide Item -->\r\n                        <div class=\"slide-item\">\r\n                            <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2022\/08\/technology-ga9252e811_1920.jpg);\"><\/div>\r\n                            <div class=\"shape-1\"><\/div>\r\n                            <div class=\"shape-2\"><\/div>\r\n                            <div class=\"shape-3\"><\/div>\r\n                            <div class=\"shape-4\"><\/div>\r\n                            <div class=\"shape-5\"><\/div>\r\n                            <div class=\"shape-6\"><\/div>\r\n                            <div class=\"auto-container\">\r\n                                <div class=\"content-box\">\r\n                                    <div class=\"content\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"sub-title\">Communiquez efficacement avec votre audience<\/div>\r\n                                            <h1>Laissez faire les pros des r\u00e9seaux!<\/h1>\r\n                                            <div class=\"link-box\">\r\n                                                <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/service\/community-management\/\">\r\n                                                    <i class=\"btn-curve\"><\/i>\r\n                                                    <span class=\"btn-title\">Nous g\u00e9rons vos r\u00e9seaux sociaux<\/span>\r\n                                                <\/a>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <!-- Slide Item -->\r\n                        <div class=\"slide-item\">\r\n                            <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2022\/08\/the-new-york-public-library-h69C5AlUG8-unsplash-scaled.jpg);\"><\/div>\r\n                            <div class=\"shape-1\"><\/div>\r\n                            <div class=\"shape-2\"><\/div>\r\n                            <div class=\"shape-3\"><\/div>\r\n                            <div class=\"shape-4\"><\/div>\r\n                            <div class=\"shape-5\"><\/div>\r\n                            <div class=\"shape-6\"><\/div>\r\n                            <div class=\"auto-container\">\r\n                                <div class=\"content-box\">\r\n                                    <div class=\"content\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"sub-title\">R\u00e9v\u00e9lez votre leadership en ligne !<\/div>\r\n                                            <h1>Top Leader : D\u00e9veloppez votre pr\u00e9sence en ligne <\/h1>\r\n                                            <div class=\"link-box\">\r\n                                                <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/fr\/service\/personal-branding\/\">\r\n                                                    <i class=\"btn-curve\"><\/i>\r\n                                                    <span class=\"btn-title\">Personal Branding<\/span>\r\n                                                <\/a>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                            <!-- Slide Item -->\r\n                        <div class=\"slide-item\">\r\n                            <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/firmbee-com-jrh5lAq-mIs-unsplash-scaled.jpg);\"><\/div>\r\n                            <div class=\"shape-1\"><\/div>\r\n                            <div class=\"shape-2\"><\/div>\r\n                            <div class=\"shape-3\"><\/div>\r\n                            <div class=\"shape-4\"><\/div>\r\n                            <div class=\"shape-5\"><\/div>\r\n                            <div class=\"shape-6\"><\/div>\r\n                            <div class=\"auto-container\">\r\n                                <div class=\"content-box\">\r\n                                    <div class=\"content\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"sub-title\">Les meilleures techniques pour vous rendre c\u00e9l\u00e8bre et cr\u00e9dible<\/div>\r\n                                            <h1>Cr\u00e9dibilit\u00e9 &amp; Notori\u00e9t\u00e9 exponentielles<\/h1>\r\n                                            <div class=\"link-box\">\r\n                                                <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/entrez-dans-lere-numeractive\/\">\r\n                                                    <i class=\"btn-curve\"><\/i>\r\n                                                    <span class=\"btn-title\">D\u00c9COUVREZ L&#039;\u00c8RE NUMERACTIVE<\/span>\r\n                                                <\/a>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    \r\n                <\/div>\r\n            <\/section>\r\n            <!--End Banner Section -->\r\n\r\n        \r\n        \r\n        <!-- layout four -->\r\n        \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec28987 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ec28987\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e543c6\" data-id=\"7e543c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5411d0c elementor-widget elementor-widget-linoor-funfact\" data-id=\"5411d0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n                    <!-- Funfacts Section -->\r\n            <section class=\"facts-section alternate\">\r\n                <div class=\"auto-container\">\r\n                    <div class=\"inner-container\">\r\n                        <!-- Fact Counter -->\r\n                        <div class=\"fact-counter\">\r\n                            <div class=\"row clearfix\">\r\n                                                                    <!--Column-->\r\n                                    <div class=\"column counter-column col-lg-3 col-md-6 col-sm-12\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"content\">\r\n                                                <div class=\"count-outer count-box\">\r\n                                                    <span class=\"count-text\" data-speed=\"4000\" data-stop=\"196\">0<\/span>\r\n                                                <\/div>\r\n                                                <div class=\"counter-title\">PROJETS TERMIN\u00c9S<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                    <!--Column-->\r\n                                    <div class=\"column counter-column col-lg-3 col-md-6 col-sm-12\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"content\">\r\n                                                <div class=\"count-outer count-box\">\r\n                                                    <span class=\"count-text\" data-speed=\"4000\" data-stop=\"987600\">0<\/span>\r\n                                                <\/div>\r\n                                                <div class=\"counter-title\">CHF g\u00e9n\u00e9r\u00e9s<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                    <!--Column-->\r\n                                    <div class=\"column counter-column col-lg-3 col-md-6 col-sm-12\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"content\">\r\n                                                <div class=\"count-outer count-box\">\r\n                                                    <span class=\"count-text\" data-speed=\"4000\" data-stop=\"6\">0<\/span>\r\n                                                <\/div>\r\n                                                <div class=\"counter-title\">Pays diff\u00e9rents<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                                    <!--Column-->\r\n                                    <div class=\"column counter-column col-lg-3 col-md-6 col-sm-12\">\r\n                                        <div class=\"inner\">\r\n                                            <div class=\"content\">\r\n                                                <div class=\"count-outer count-box\">\r\n                                                    <span class=\"count-text\" data-speed=\"4000\" data-stop=\"135\">0<\/span>\r\n                                                <\/div>\r\n                                                <div class=\"counter-title\">CLIENTS HEUREUX<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n            <!-- End Funfacts Section -->\r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7ab246 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"d7ab246\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6781481\" data-id=\"6781481\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08f8b46 elementor-widget elementor-widget-linoor-service\" data-id=\"08f8b46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-service.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        \r\n            <!--Services Section-->\r\n            <section class=\"services-section-two\">\r\n                <div class=\"auto-container\">\r\n                                            <div class=\"sec-title\">\r\n                            <!--Title Block-->\r\n                            <div class=\"row clearfix\">\r\n                                <div class=\"column col-xl-6 col-lg-12 col-md-12 col-sm-12\">\r\n                                    <h2>Devenir <span class=\"dot\">c\u00e9l\u00e8bre<\/span> et <span class=\"dot\">cr\u00e9dible<\/SPAN> ?\n<br \/>C'est possible !<\/h2>\r\n                                <\/div>\r\n                                <div class=\"column col-xl-6 col-lg-12 col-md-12 col-sm-12\">\r\n                                    <div class=\"lower-text\">En lan\u00e7ant votre entreprise, avez-vous envisag\u00e9 l'importance cruciale de votre pr\u00e9sence en ligne et de votre personal branding ? \n<b>En tant que leader suisse du personal branding et de la prospection B2B, nous sommes l\u00e0 pour vous guider. <\/b>\n<br><br>\nLe marketing digital est l'\u00e9pine dorsale de cette pr\u00e9sence en ligne. \nAvec des strat\u00e9gies bien con\u00e7ues, le marketing digital transforme votre pr\u00e9sence en ligne en un puissant outil de croissance et de r\u00e9ussite commerciale. <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"services\">\r\n                        <div class=\"row clearfix\">\r\n                                        <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" fab\"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/prospezione-linkedin\/\">Automatisation de la prospection<\/a><\/h5>\r\n                    <div class=\"text\">Gagnez du temps, gagnez des clients :\u00a0l&#039;automatisation de la prospection\u00a0Chez NUMERACTIVE, nous comprenons l&#039;importance cruciale de d\u00e9velopper des strat\u00e9gies de prospection efficaces<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/prospezione-linkedin\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" fas\"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/influencer-tv-stampa\/\">Personal Branding<\/a><\/h5>\r\n                    <div class=\"text\">Fa\u00e7onner Votre Identit\u00e9 Digitale avec le Personal BrandingLe personal branding \u00e9merge comme une strat\u00e9gie indispensable pour les individus ambitieux et soucieux de<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/influencer-tv-stampa\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" fab\"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/pubblicita-sponsorizzata\/\">Publicit\u00e9 Sponsoris\u00e9e<\/a><\/h5>\r\n                    <div class=\"text\">Comment promouvoir les services de sa soci\u00e9t\u00e9? Comment vendre les produits de son entreprise sur Internet? Gr\u00e2ce aux publicit\u00e9s sponsoris\u00e9es bien s\u00fbr!<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/pubblicita-sponsorizzata\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" \"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/gestione-della-comunita\/\">Community Management<\/a><\/h5>\r\n                    <div class=\"text\">Engagez, Interagissez, Prosp\u00e9rez : votre communaut\u00e9, notre expertise Au c\u0153ur de toute strat\u00e9gie digitale r\u00e9ussie, r\u00e9side dans une gestion quotidienne attentive et<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/gestione-della-comunita\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" \"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/sito-web-di-riferimento\/\">Site Web<\/a><\/h5>\r\n                    <div class=\"text\">Votre Site Web, notre savoir-faire Votre site web est bien plus qu&#039;une simple pr\u00e9sence en ligne. Il est le reflet de votre<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/sito-web-di-riferimento\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                    <!--Service Block-->\r\n            <div class=\"service-block-two col-xl-3 col-lg-6 col-md-6 col-sm-12\">\r\n                <div class=\"inner-box wow fadeInUp\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                    <div class=\"bottom-curve\"><\/div>\r\n                                        <div class=\"icon-box\"><span class=\" \"><\/span><\/div>\r\n                    <h5><a href=\"https:\/\/numeractive.ch\/it\/servizio\/seo\/\">R\u00e9f\u00e9rencement<\/a><\/h5>\r\n                    <div class=\"text\">En pole position sur le Web Notre savoir-faire en r\u00e9f\u00e9rencement Aujourd&#039;hui, \u00eatre visible en ligne est essentiel pour la r\u00e9ussite de toute<\/div>\r\n                    <div class=\"link-box\"><a href=\"https:\/\/numeractive.ch\/it\/servizio\/seo\/\"><span class=\"fa fa-angle-right\"><\/span><\/a><\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n        \r\n        \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b267e31 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b267e31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57d6561\" data-id=\"57d6561\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a28272 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-linoor-sponsors\" data-id=\"8a28272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-sponsors.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n                    <!--Sponsors Section-->\r\n            <section class=\"sponsors-section-two\">\r\n                <div class=\"auto-container\">\r\n                    <!--Sponsors Carousel-->\r\n                    <div class=\"row clearfix\">\r\n                        <div class=\"title-col col-xl-5 col-lg-12 col-md-12\">\r\n                            <div class=\"sec-title wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                <h2>ILS NOUS FONT CONFIANCE<span class=\"dot\">.<\/span><\/h2>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class=\"logo-col col-xl-7 col-lg-12 col-md-12\">\r\n                            <div class=\"row clearfix\">\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/www.allergan.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"Allergan an AbbVie Company\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"Allergan an AbbVie Company\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/vaudoise.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/swisslife-select.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/SLS_Logo.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/SLS_Logo.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/evok.com\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=18%2C5&amp;ssl=1 18w\" width=\"150\" height=\"48\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"48\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=18%2C5&amp;ssl=1 18w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/4-b.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/forum-arc.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/new.swissmovie.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=138%2C70&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?w=138&amp;ssl=1 138w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=18%2C9&amp;ssl=1 18w\" width=\"138\" height=\"70\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"logo_swissmovie\"  sizes=\"(max-width: 138px) 100vw, 138px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"70\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=138%2C70&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"logo_swissmovie\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?w=138&amp;ssl=1 138w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=18%2C9&amp;ssl=1 18w\" sizes=\"(max-width: 138px) 100vw, 138px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/etudeferraz.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"etude_ferraz_logo\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"etude_ferraz_logo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/de-blasio.opel.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/www.arom.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger-1.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger-1.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/lspartners.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=18%2C9&amp;ssl=1 18w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"LS Partners\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"LS Partners\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=18%2C9&amp;ssl=1 18w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                <\/div>\r\n            <\/section>\r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09bd35a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"09bd35a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18b60db\" data-id=\"18b60db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2beebc7 elementor-widget elementor-widget-linoor-featured\" data-id=\"2beebc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-featured.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n                    <!--Featured Section-->\r\n            <section class=\"featured-section\">\r\n                <div class=\"auto-container\">\r\n                    <div class=\"row clearfix\">\r\n                        <!--Left Column-->\r\n                        <div class=\"left-col col-lg-6 col-md-12 col-sm-12\">\r\n                            <div class=\"inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                <div class=\"image-box\"><img decoding=\"async\" class=\"lazyload\" data-src=\"http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/08\/kl.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/kl.jpg\" alt=\"\"><\/noscript><\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                        <!--Right Column-->\r\n                        <div class=\"right-col col-lg-6 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                                                    <div class=\"sec-title\">\r\n                                        <h2>UN LARGE R\u00c9SEAU D\u2019EXPERTS<span class=\"dot\">.<\/span><\/h2>\r\n                                        <div class=\"lower-text\">Vous avez une demande complexe et vos ressources techniques sont insuffisantes pour la r\u00e9aliser ?  <br>Pas de panique ! Nous avons acc\u00e8s \u00e0 un grand r\u00e9seau d'experts qui vous offre un large \u00e9ventail de comp\u00e9tences. <BR><b>Nous actionnons nos diff\u00e9rents leviers pour vous offrir les comp\u00e9tences les plus adapt\u00e9es \u00e0 vos besoins.<\/b><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"features\">\r\n                                    <div class=\"row clearfix\">\r\n                                                                                    <div class=\"feature col-md-6 col-sm-12\">\r\n                                                <div class=\"inner-box\">\r\n                                                    <h6>Z\u00c9RO LIMITE<\/h6>\r\n                                                    <div class=\"text\">Nous n\u2019avons pas froid au yeux: nous r\u00e9alisons petits et grands projets.<\/div>\r\n                                                <\/div>\r\n                                            <\/div>\r\n                                                                                    <div class=\"feature col-md-6 col-sm-12\">\r\n                                                <div class=\"inner-box\">\r\n                                                    <h6>POUR TOUS LES BUDGETS<\/h6>\r\n                                                    <div class=\"text\">En fonction de votre objectif et de votre budget, nous adaptons notre offre proportionnellement.<\/div>\r\n                                                <\/div>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n        \r\n        \r\n        \r\n\r\n        \r\n        \r\n        \r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6cae577 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cae577\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9b48e83\" data-id=\"9b48e83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f3a6b elementor-widget elementor-widget-heading\" data-id=\"86f3a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos clients t\u00e9moignent<span class=\"dot\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12a327a elementor-widget elementor-widget-shortcode\" data-id=\"12a327a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-disable-font ti-show-rating-text ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"il y a %d %s|aujourd&apos;hui|jour|jours|semaine|semaines|mois|mois|ann\u00e9e|ans\" data-plugin-version=\"13.3.2\" data-layout-id=\"34\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"fr\" data-close-locale=\"Fermer\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"R\u00e9ponse du propri\u00e9taire\" data-only-rating-locale=\"Cet utilisateur a uniquement laiss\u00e9 une \u00e9valuation.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-header ti-header-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELLENT <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Bas\u00e9e sur <strong>25 avis<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Avis suivante\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Avis pr\u00e9c\u00e9dent\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1718150400\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIRrY_dh3M-utogsJqBm2hDOSVHU5W1Vmrj3_hYvzz8UFBYvA=w40-h40-c-rp-mo-br100\" alt=\"Guess Guess profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Guess Guess <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Tr\u00e8s professionel et efficace. Je  ne peux que  les reccomander<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1717027200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL7ox_jUa6DwQyOvq32VmucawaP9UUR9KrQlQoItM_ZTiEUaQ=w40-h40-c-rp-mo-br100\" alt=\"UpGrade UpGrade profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> UpGrade UpGrade <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->En un seul conseil  Florian a r\u00e9ussit \u00e0 d\u00e9bloquer ma prospection. Tr\u00e8s pro, un immense merci Numeractive<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1709683200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVl2Kx6bRdoQdwsRlONJMIp8Q7NtWSJ5ibwOLVF3E2WsChDerRB=w40-h40-c-rp-mo-ba2-br100\" alt=\"Laure Haldimann profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Laure Haldimann <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Service au TOP ! Merci beaucoup pour ton travail dans mes projets qui m'a \u00e9t\u00e9 d'une aide pr\u00e9cieuse ! J'esp\u00e8re avoir d'autres opportunit\u00e9s de travailler avec toi.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1687824000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLNVsTwIDzSAHbPrpddXO6a0OdL2MzkglRVtJHb3rRQxO2Sew=w40-h40-c-rp-mo-br100\" alt=\"Jean Romathier profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jean Romathier <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Entreprise parfaite, les objectifs ont \u00e9t\u00e9 plus are atteint<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1687824000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUMK4QEXVG-0rTZjCcZdo1_iJzJWpMkTzKDEdVUiLHex3JeYc4=w40-h40-c-rp-mo-br100\" alt=\"M\u00e9ril Hinavako profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> M\u00e9ril Hinavako <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Merci pour leur precision et leur fa\u00e7on ee faire unique<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1687824000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJLDLHHXqaIacI44b0BZPkYBX07yAgQA8sBjGXbpG3PE6e42w=w40-h40-c-rp-mo-br100\" alt=\"Meher Akin profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Meher Akin <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Professionnalisme!!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1687824000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL4puv6gXOY-ueAEiSDJQ9DWw3lPa_h2Bz3y24sMk0rMYyIQw=w40-h40-c-rp-mo-br100\" alt=\"Lecturas S\u00e0rl profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Lecturas S\u00e0rl <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->L\u2019\u00e9quipe de numeractive a \u00e9t\u00e9 tr\u00e8s professionnelle et a r\u00e9alis\u00e9 nos attentes avec perfection<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"1\" data-time=\"1663459200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJNnHlq-kDy7pMv2PzFJEZ4076A_r9CvlV0plO1Til-rYGdzw=w40-h40-c-rp-mo-br100\" alt=\"Pierre-Alain Angeretti profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Pierre-Alain Angeretti <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1650585600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJV0VhjDIDViIIYdlEjJfn2xRlmnzCo98e-nGOIubpR-ErwWQ=w40-h40-c-rp-mo-br100\" alt=\"Chris profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Chris <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Merci Florian pour toutes ces petites astuces qui font la diff\u00e9rence.\nPlein succ\u00e8s pour la suite !!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1650585600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK9LoUyoQIBidENSBDxfjc78TPgcv9FbZ5PT0C1_hJcbzbXIQ=w40-h40-c-rp-mo-br100\" alt=\"Fr\u00e9d\u00e9ric Leu profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Fr\u00e9d\u00e9ric Leu <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Top formation et \u00e9change avec Florian! Un grand merci!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>   <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/numeractive.ch\/wp-content\/uploads\/trustindex-google-widget.css?1787105033\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c812a32 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c812a32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2cc6da\" data-id=\"c2cc6da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0372a88 elementor-hidden-phone elementor-widget elementor-widget-linoor-portfolio\" data-id=\"0372a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        \r\n\r\n        \r\n            <!-- Gallery Section -->\r\n            <section class=\"gallery-section-two alternate\">\r\n                <div class=\"auto-container\">\r\n                                            <div class=\"sec-title centered\">\r\n                            <h2>NOS DIFF\u00c9RENTS MANDATS<span class=\"dot\">.<\/span><\/h2>\r\n                        <\/div>\r\n                    \r\n                <\/div>\r\n                <!--Porfolio Tabs-->\r\n                <div class=\"project-tab\">\r\n                    <div class=\"auto-container\">\r\n                        <div class=\"tab-btns-box\">\r\n\r\n                                                                                        <!--Tabs Header-->\r\n                                <div class=\"tabs-header\">\r\n                                    <ul class=\"product-tab-btns clearfix ml-0 list-unstyled\">\r\n\r\n                                        <!--Filter-->\r\n                                        <li class=\"filters clearfix\">\r\n                                            <ul class=\"filter-tabs filter-btns clearfix m-0 list-unstyled\">\r\n\r\n                                                                                                                                                        <li class=\"p-tab-btn active-btn\" data-tab=\"#p2-tab-1\">Design<sup>[12]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-2\">Event<sup>[1]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-3\">Influencing<sup>[2]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-4\">LinkedIn<sup>[11]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-5\">Publicit\u00e9<sup>[8]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-6\">R\u00e9seaux sociaux<sup>[14]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-7\">Site Web<sup>[18]<\/sup><\/li>\r\n                                                                                                                                                                                                            <li class=\"p-tab-btn \" data-tab=\"#p2-tab-8\">Vid\u00e9o<sup>[5]<\/sup><\/li>\r\n                                                                                                                                                <\/ul>\r\n                                        <\/li>\r\n\r\n                                    <\/ul>\r\n                                <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                    <div class=\"auto-container\">\r\n                        <!--Tabs Content-->\r\n                        <div class=\"p-tabs-content\">\r\n\r\n                                                                                                                                                                <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab active-tab\" id=\"p2-tab-1\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Fri-Fight Academy - Design\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Fri-Fight Academy - Design\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Fri-Fight-Academy.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/progettazione-della-lotta-dellaccademia-di-venerdi\/\">Fri-Fight Academy &#8211; Design<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Duperrez Metal - Publicit\u00e9 dans la presse\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Duperrez Metal - Publicit\u00e9 dans la presse\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DUPERREX_Journal.png?fit=1300%2C1955&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/duperrex-metal-advertising-press\/\">Duperrex Metal &#8211; Publicit\u00e9 Presse<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"De Blasio Automobiles - R\u00e9seaux sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"De Blasio Automobiles - R\u00e9seaux sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?fit=994%2C860&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/de-blasio-automobili-social-networks\/\">De Blasio Automobiles &#8211; R\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GarageConcept Vid\u00e9o promo\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GarageConcept Vid\u00e9o promo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?fit=1874%2C929&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/concept-automobiles-promotional-video-and-advertising-target\/\">Concept Automobiles &#8211; Vid\u00e9o promotionnelle et publicit\u00e9 cibl\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?resize=370%2C136&amp;ssl=1\" width=\"370\" height=\"136\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"AB Electronics\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"136\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?resize=370%2C136&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"AB Electronics\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?fit=463%2C136&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ab-electronics-site-web-e-commerce\/\">AB Electronics &#8211; site web e-commerce<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"BNI Gruy\u00e8re\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"BNI Gruy\u00e8re\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?fit=934%2C769&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/bni-reti-sociali\/\">BNI &#8211; Strat\u00e9gie de r\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Vid\u00e9o \u00c9tude Ferraz\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Vid\u00e9o \u00c9tude Ferraz\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?fit=1812%2C915&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/studio-ferraz-video-presentazione\/\">\u00c9tude Ferraz &#8211; Cr\u00e9ation d&rsquo;une vid\u00e9o de pr\u00e9sentation<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"RENOCREA - Logo\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"RENOCREA - Logo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/renocrea.png?fit=857%2C613&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/renocrea-immagine-di-mercato-logo-visite-carte\/\">RENOCREA &#8211; Logo et cartes de visite<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Site web B-nergy\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Site web B-nergy\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?fit=1615%2C880&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/b-nergy-website-and-brand-image\/\">B-NERGY &#8211; Site web et image de marque<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GC-EM site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GC-EM site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?fit=1412%2C922&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/garage-carrosserie-e-m-site-web-and-video-promotional-advertising\/\">Garage-Carrosserie E.M. &#8211; Site web et vid\u00e9o promotionnelle<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=270%2C270&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?w=270&amp;ssl=1 270w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=73%2C73&amp;ssl=1 73w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=100%2C100&amp;ssl=1 100w\" width=\"270\" height=\"270\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"\"  sizes=\"(max-width: 270px) 100vw, 270px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"270\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=270%2C270&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?w=270&amp;ssl=1 270w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=73%2C73&amp;ssl=1 73w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 270px) 100vw, 270px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?fit=270%2C270&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Design<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/viatransports-ch-site-web\/\">Viatransports.ch &#8211; Site web vitrine<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-2\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Allergan by Abbvie - Application \u00e9v\u00e9nementielle streaming\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Allergan by Abbvie - Application \u00e9v\u00e9nementielle streaming\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abbvie-1.jpg?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Event<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/allergan-application-event-streaming\/\">Allergan by Abbvie &#8211; Application \u00e9v\u00e9nementielle + streaming<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-3\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?fit=1710%2C2560&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Influencing<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sponsorizzata-da-laure-haldimann\/\">Laure Haldimann &#8211; Publicit\u00e9 Sponsoris\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Influencing<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-4\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Events Sport SA - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Events Sport SA - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Events-Sport-SA.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/acquisizione-clienti-linkedin\/\">Events Sport SA &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"eHall SA - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"eHall SA - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/eHall-SA.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ehall-sa-acquisizione-clienti-linkedin\/\">eHall SA &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Swiss Life Select Schweiz AG - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Swiss Life Select Schweiz AG - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Swiss-Life-Select-Schweiz-AG.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/swiss-life-select-schweiz-ag\/\">Swiss Life Select Schweiz AG &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"FCG Swiss - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"FCG Swiss - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/FCG-Swiss.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/acquisizione-clienti-fcg-swiss-linkedin\/\">FCG Swiss &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"CardiAid Suisse - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"CardiAid Suisse - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CardiAid-Suisse-Acquisition-de-clients.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/acquisizione-clienti-cardioid-svizzera-linkedin\/\">CardiAid Suisse &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"CPOrg - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"CPOrg - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/CPOrg-Acquisition-de-clients-LinkedIn.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/acquisizione-clienti-cporg-linkedin\/\">CPOrg &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Fearless Transformation - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Fearless Transformation - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-2.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/trasformazione-senza-paura-legata-allacquisizione-di-clienti\/\">Fearless Transformation &#8211; Acquisition de client LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/4B-AG-Photo-e1706606208377.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/4B-AG-Photo-e1706606208377.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/4B-AG-Photo-e1706606208377.png?fit=618%2C586&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/acquisizione-clienti-4b-ag-tramite-linkedin\/\">4B AG &#8211; Acquisition de clients via LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"eHall - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"eHall - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-205046.jpg?fit=1862%2C885&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ehall-acquisizione-di-clienti-via-linkedin\/\">eHall &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Swissmovie - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Swissmovie - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204738.jpg?fit=939%2C437&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/swissmovie-customer-acquisition-linkedin\/\">Swissmovie &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"AROM - Acquisition de clients via LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"AROM - Acquisition de clients via LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-11-234439.jpg?fit=893%2C752&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>LinkedIn<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/arom-consulting-client-acquisizione-via-linkedin\/\">AROM Consulting &#8211; Acquisition de clients via LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-5\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?fit=1710%2C2560&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sponsorizzata-da-laure-haldimann\/\">Laure Haldimann &#8211; Publicit\u00e9 Sponsoris\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"O-Poil Toilettage - Publicit\u00e9\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"O-Poil Toilettage - Publicit\u00e9\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/O-Poil-Toilettage-Publicite.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/o-pubblicita-sulla-cura-dei-capelli\/\">O-Poil Toilettage &#8211; Publicit\u00e9<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Global Atittude - Publicit\u00e9\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Global Atittude - Publicit\u00e9\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Global-Atittude.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/atteggiamento-generale\/\">Global Atittude &#8211; Publicit\u00e9<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"SwissAlps Solar - R\u00e9seaux Sociaux et Publicit\u00e9\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"SwissAlps Solar - R\u00e9seaux Sociaux et Publicit\u00e9\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?fit=600%2C570&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sui-social-network-solari-di-swissalps\/\">SwissAlps Solar &#8211; R\u00e9seaux Sociaux &#8211; Publicit\u00e9<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"R\u00e9seau Choix Vaccinal - Publicit\u00e9 cibl\u00e9e sur r\u00e9seaux sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"R\u00e9seau Choix Vaccinal - Publicit\u00e9 cibl\u00e9e sur r\u00e9seaux sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?fit=2001%2C952&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/network-choice-vaccine-advertising-targeted-on-social-networks\/\">R\u00e9seau Choix Vaccinal &#8211; Publicit\u00e9 cibl\u00e9e sur les r\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GarageConcept Vid\u00e9o promo\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GarageConcept Vid\u00e9o promo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?fit=1874%2C929&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/concept-automobiles-promotional-video-and-advertising-target\/\">Concept Automobiles &#8211; Vid\u00e9o promotionnelle et publicit\u00e9 cibl\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GC-EM site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GC-EM site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?fit=1412%2C922&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/garage-carrosserie-e-m-site-web-and-video-promotional-advertising\/\">Garage-Carrosserie E.M. &#8211; Site web et vid\u00e9o promotionnelle<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Publicit\u00e9<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-6\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?fit=1710%2C2560&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sponsorizzata-da-laure-haldimann\/\">Laure Haldimann &#8211; Publicit\u00e9 Sponsoris\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"MMT Sarl -ReseauxSociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"MMT Sarl -ReseauxSociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/MMT-Sarl-Reseaux-Sociaux.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/social-network-mmt-sarl\/\">MMT S\u00e0rl &#8211; R\u00e9seaux Sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"A. Rosselet SA - R\u00e9seaux Sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"A. Rosselet SA - R\u00e9seaux Sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/04\/A.-Rosselet-SA.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/il-nostro-servizio-di-gestione-della-comunita\/\">A. Rosselet SA &#8211; R\u00e9seaux Sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"LS Partners - Acquisition de clients LinkedIn\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"LS Partners - Acquisition de clients LinkedIn\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/LS-Partners.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ls-partner-linkedin-acquisizione-clienti\/\">LS Partners &#8211; Acquisition de clients LinkedIn<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GL\u00d4BAT IMMO - R\u00e9seaux Sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GL\u00d4BAT IMMO - R\u00e9seaux Sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/GLOBAT-IMMO.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/social-network-immo-globali\/\">GL\u00d4BAT IMMO &#8211; R\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Horions Digital Technologies - R\u00e9seaux Sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Horions Digital Technologies - R\u00e9seaux Sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Horions.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/orizzonti-tecnologie-digitali-social-network\/\">Horions Digital Technologies &#8211; R\u00e9seaux Sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"SwissAlps Solar - R\u00e9seaux Sociaux et Publicit\u00e9\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"SwissAlps Solar - R\u00e9seaux Sociaux et Publicit\u00e9\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats-1.png?fit=600%2C570&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sui-social-network-solari-di-swissalps\/\">SwissAlps Solar &#8211; R\u00e9seaux Sociaux &#8211; Publicit\u00e9<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Concept Automobiles SA\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Concept Automobiles SA\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Concept-Automobiles-SA.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/concept-car-nei-social-network\/\">Concept Automobiles SA &#8211; R\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Sarine Parquet - R\u00e9seaux sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Sarine Parquet - R\u00e9seaux sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-203817.jpg?fit=903%2C739&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sarine-parquet-reseaux-sociaux\/\">Sarine Parquet &#8211; Cr\u00e9ation des R\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"R\u00e9seau Choix Vaccinal - Publicit\u00e9 cibl\u00e9e sur r\u00e9seaux sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"R\u00e9seau Choix Vaccinal - Publicit\u00e9 cibl\u00e9e sur r\u00e9seaux sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/8KW9ZYLOaGv8WT884VdcH2.jpg?fit=2001%2C952&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/network-choice-vaccine-advertising-targeted-on-social-networks\/\">R\u00e9seau Choix Vaccinal &#8211; Publicit\u00e9 cibl\u00e9e sur les r\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"De Blasio Automobiles - R\u00e9seaux sociaux\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"De Blasio Automobiles - R\u00e9seaux sociaux\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/deblasio.png?fit=994%2C860&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/de-blasio-automobili-social-networks\/\">De Blasio Automobiles &#8211; R\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"BNI Gruy\u00e8re\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"BNI Gruy\u00e8re\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/bni_gruyerePNG.png?fit=934%2C769&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/bni-reti-sociali\/\">BNI &#8211; Strat\u00e9gie de r\u00e9seaux sociaux<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GC-EM site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GC-EM site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?fit=1412%2C922&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/garage-carrosserie-e-m-site-web-and-video-promotional-advertising\/\">Garage-Carrosserie E.M. &#8211; Site web et vid\u00e9o promotionnelle<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>R\u00e9seaux sociaux<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-7\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Rinascimiento - Site Web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Rinascimiento - Site Web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/03\/Rinascimiento.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-del-risciacquo\/\">Rinascimiento &#8211; Site Web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Black-Shop-Site-Web.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-della-spa-nera\/\">Black Spa &#8211; Site Web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"UA Solutions - R\u00e9f\u00e9rencement\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"UA Solutions - R\u00e9f\u00e9rencement\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Image-en-arriere-plan-Site-1.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ua-soluzioni-seo\/\">UA Solutions &#8211; R\u00e9f\u00e9rencement<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Plumettaz - Site Web - R\u00e9f\u00e9rencement\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Plumettaz - Site Web - R\u00e9f\u00e9rencement\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Miniature-Mandats.png?fit=600%2C570&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/seo-del-sito-plumettaz\/\">PLUMETTAZ &#8211; Site Web \/ R\u00e9f\u00e9rencement<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Concept-Automobiles-SA-600-x-570-px.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"EVOK - Site Web - R\u00e9f\u00e9rencement\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Concept-Automobiles-SA-600-x-570-px.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"EVOK - Site Web - R\u00e9f\u00e9rencement\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/02\/Concept-Automobiles-SA-600-x-570-px.png?fit=600%2C570&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/evocare-il-seo-del-sito-web\/\">EVOK &#8211; Site Web \/ R\u00e9f\u00e9rencement<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Agibility\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Agibility\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-1-e1706606761475.png?fit=745%2C586&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-di-agilita\/\">Agilbility &#8211; Site web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-e1706606635418.png?resize=370%2C426&amp;ssl=1\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"AFI Conseil Site web\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-e1706606635418.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"AFI Conseil Site web\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/AFI-Conseil-e1706606635418.png?fit=661%2C586&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-di-consulenza-afi\/\">AFI Conseils &#8211; Site web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Abracadabra Cr\u00e9ativit\u00e9 Inspir\u00e9e Site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Abracadabra Cr\u00e9ativit\u00e9 Inspir\u00e9e Site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/01\/Abracadabra.png?fit=880%2C587&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-di-creativita-ispirata-ad-abracadabra\/\">Abracadabra Cr\u00e9ativit\u00e9 Inspir\u00e9e &#8211; Site web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"ABC Metal - Site web vitrine\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"ABC Metal - Site web vitrine\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/abcmetal.png?fit=1431%2C897&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/abc-metal-site-web\/\">ABC Metal &#8211; Site web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Swiss Marketing L\u00e9man - Site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Swiss Marketing L\u00e9man - Site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-204101.jpg?fit=1532%2C851&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/sito-web-di-swiss-marketing-leman\/\">Swiss Marketing L\u00e9man &#8211; Site web vitrine<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"METALCORP Site web vitrine\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"METALCORP Site web vitrine\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200657.jpg?fit=1849%2C862&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/metalcorp-website-window\/\">METALCORP &#8211; Site web vitrine<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Kasper Clean - Site web vitrine\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Kasper Clean - Site web vitrine\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Capture-decran-2021-12-13-200149.jpg?fit=1370%2C830&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/kasper-clean-site-web\/\">Kasper Clean &#8211; Site web<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?resize=370%2C136&amp;ssl=1\" width=\"370\" height=\"136\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"AB Electronics\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"136\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?resize=370%2C136&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"AB Electronics\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/09\/abelectronics.png?fit=463%2C136&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/ab-electronics-site-web-e-commerce\/\">AB Electronics &#8211; site web e-commerce<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Site web B-nergy\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Site web B-nergy\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/b-nergyPNG.png?fit=1615%2C880&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/b-nergy-website-and-brand-image\/\">B-NERGY &#8211; Site web et image de marque<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GC-EM site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GC-EM site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?fit=1412%2C922&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/garage-carrosserie-e-m-site-web-and-video-promotional-advertising\/\">Garage-Carrosserie E.M. &#8211; Site web et vid\u00e9o promotionnelle<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=270%2C270&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?w=270&amp;ssl=1 270w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=73%2C73&amp;ssl=1 73w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=100%2C100&amp;ssl=1 100w\" width=\"270\" height=\"270\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"\"  sizes=\"(max-width: 270px) 100vw, 270px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"270\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=270%2C270&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?w=270&amp;ssl=1 270w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=73%2C73&amp;ssl=1 73w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 270px) 100vw, 270px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/screenshot-1-270x270-1.png?fit=270%2C270&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/viatransports-ch-site-web\/\">Viatransports.ch &#8211; Site web vitrine<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Site web Amasol\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Site web Amasol\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/01\/Capture-decran-2021-12-11-215400.jpg?fit=1197%2C701&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Site Web<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/amasol-website-window\/\">Amasol.ch &#8211; Site web vitrine<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                                                            <!--Portfolio Tab \/ Active Tab-->\r\n                                    <div class=\"p-tab \" id=\"p2-tab-8\">\r\n                                        <div class=\"project-carousel-two owl-theme owl-carousel\">\r\n                                            \r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Laure Haldimann - Publicit\u00e9 Sponsoris\u00e9e\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/07\/DSC01353-scaled.jpg?fit=1710%2C2560&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Vid\u00e9o<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/pubblicita-sponsorizzata-da-laure-haldimann\/\">Laure Haldimann &#8211; Publicit\u00e9 Sponsoris\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GarageConcept Vid\u00e9o promo\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GarageConcept Vid\u00e9o promo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/GarageConcept.png?fit=1874%2C929&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Vid\u00e9o<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/concept-automobiles-promotional-video-and-advertising-target\/\">Concept Automobiles &#8211; Vid\u00e9o promotionnelle et publicit\u00e9 cibl\u00e9e<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Vid\u00e9o \u00c9tude Ferraz\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Vid\u00e9o \u00c9tude Ferraz\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/ferraz_video.png?fit=1812%2C915&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Vid\u00e9o<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/studio-ferraz-video-presentazione\/\">\u00c9tude Ferraz &#8211; Cr\u00e9ation d&rsquo;une vid\u00e9o de pr\u00e9sentation<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"GC-EM site web\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"GC-EM site web\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?zoom=3&amp;resize=370%2C426&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GC-EM.png?fit=1412%2C922&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Vid\u00e9o<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/garage-carrosserie-e-m-site-web-and-video-promotional-advertising\/\">Garage-Carrosserie E.M. &#8211; Site web et vid\u00e9o promotionnelle<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                            \r\n                                                \r\n                                                <!-- Gallery Item -->\r\n                                                <div class=\"gallery-item\">\r\n                                                    <div class=\"inner-box\">\r\n                                                        <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" width=\"370\" height=\"426\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image lazyload\" alt=\"Great Swiss Beauty - Influenceur\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"426\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1\" class=\"attachment-linoor_370X426 size-linoor_370X426 wp-post-image\" alt=\"Great Swiss Beauty - Influenceur\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?resize=370%2C426&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?zoom=2&amp;resize=370%2C426&amp;ssl=1 740w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript><\/figure>\r\n                                                        <a href=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/GSB.png?fit=930%2C859&#038;ssl=1\" class=\"lightbox-image overlay-box\" data-fancybox=\"gallery\"><\/a>\r\n                                                        <div class=\"cap-box\">\r\n                                                            <div class=\"cap-inner\">\r\n                                                                <div class=\"cat\"><span>Vid\u00e9o<\/span><\/div>\r\n                                                                <div class=\"title\">\r\n                                                                    <h5><a href=\"https:\/\/numeractive.ch\/it\/portafoglio\/great-swiss-beauty-influencing-social-networks\/\">Great Swiss Beauty &#8211; Influenceur de 24 abonn\u00e9s \u00e0 30&rsquo;000 en 3 mois<\/a><\/h5>\r\n                                                                <\/div>\r\n                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                                                <\/div>\r\n                                    <\/div>\r\n                                                                                                \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                <\/div>\r\n            <\/section>\r\n\r\n\r\n        \r\n                \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f6bc18 elementor-widget elementor-widget-linoor-video\" data-id=\"1f6bc18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \r\n        \r\n            <!--Why Us Section-->\r\n            <section class=\"why-us-section\">\r\n                <div class=\"auto-container\">\r\n                    <div class=\"row clearfix\">\r\n                        <!--Left Column-->\r\n                        <div class=\"left-col col-lg-6 col-md-12 col-sm-12\">\r\n                            <div class=\"inner wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                <div class=\"round-box\">\r\n                                    <div class=\"image-box\">\r\n                                        <img decoding=\"async\" class=\"lazyload\" data-src=\"http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC08025-scaled.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC08025-scaled.jpg\" alt=\"\"><\/noscript>\r\n                                    <\/div>\r\n                                    <div class=\"vid-link\">\r\n                                        <a href=\"\" class=\"lightbox-image\">\r\n                                            <div class=\"icon\"><span class=\"flaticon-play-button-1\"><\/span><i class=\"ripple\"><\/i><\/div>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                        <!--Right Column-->\r\n                        <div class=\"right-col col-lg-6 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                                                    <div class=\"sec-title\">\r\n                                        <h2><span class=\"dot\">Vous \u00eates perdus<\/span> dans le d\u00e9sert du marketing digital<span class=\"dot\">?<\/span><\/h2>\r\n                                    <\/div>\r\n                                \r\n                                <div class=\"features\">\r\n                                                                            <div class=\"feature\">\r\n                                            <div class=\"inner-box\">\r\n                                                <h6><b>L\u2019AGENCE QUI PENSE DIFF\u00c9REMMENT<\/b><\/h6>\r\n                                                <div class=\"text\">Certains disent qu\u2019on d\u00e9range, d\u2019autres nous adorent.  Notre seul motto: vous faire gagner de l\u2019argent et de la notori\u00e9t\u00e9.<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                                                            <div class=\"feature\">\r\n                                            <div class=\"inner-box\">\r\n                                                <h6><b>DES PROJETS CLAIRS ET CONCIS<\/b><\/h6>\r\n                                                <div class=\"text\">Vous avez un objectif, nous irons droit \u00e0 l\u2019essentiel ! <br>Pas de blabla inutile: nous vous cr\u00e9ons un plan d\u2019attaque et une strat\u00e9gie minutieuse.<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                                                            <div class=\"feature\">\r\n                                            <div class=\"inner-box\">\r\n                                                <h6><b>COMME DES CAM\u00c9L\u00c9ONS<\/b><\/h6>\r\n                                                <div class=\"text\">Gr\u00e2ce \u00e0 notre large r\u00e9seau, nous savons nous adapter dans n'importe quelle situation.<\/div>\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n        \r\n        \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8de3124 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8de3124\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96ff230\" data-id=\"96ff230\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b00713 elementor-widget elementor-widget-linoor-contact-form\" data-id=\"9b00713\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n            <!--Get Quote Section-->\r\n            <section class=\"get-quote-section\">\r\n                <div class=\"auto-container\">\r\n                    <div class=\"row clearfix no-gutters\">\r\n                        <!--Left Column-->\r\n                        <div class=\"left-col col-xl-8 col-lg-12 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                <div class=\"featured-block clearfix\">\r\n                                    <div class=\"image\"><img decoding=\"async\" class=\"lazyload\" data-src=\"http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/daoudi-aissa-absT1BNRDAI-unsplash-scaled.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/daoudi-aissa-absT1BNRDAI-unsplash-scaled.jpg\" alt=\"\"><\/noscript><\/div>\r\n                                    <h4><b>NOS VALEURS<\/b><\/h4>\r\n                                    <div class=\"text\"><b>TRANSPARENCE<\/b><br>\n<span>Entre nous, pas de secrets ! \nVous recevez des plans et des rapports d\u00e9taill\u00e9s pour tous vos projets\n<\/span>\n<br><br><b>RESPECT<\/b><br>\n<span>Respect mutuel entre nos clients, nos fournisseurs et nos collaborateurs: nous travaillons tous main dans la main.\n<\/span>\n<br><br><b>\u00c9COUTE<\/b><br>\n<span>On nous a donn\u00e9 deux oreilles et une bouche, nous les utilisons proportionnellement !<\/span><\/div>\r\n                                <\/div>\r\n                                <div class=\"counter\">\r\n                                    <div class=\"counter-inner clearfix\">\r\n                                        <div class=\"counter-text\">\r\n                                            <div class=\"count-box\"><span class=\"count-text\" data-stop=\"678350\" data-speed=\"2500\">0<\/span><\/div>\r\n                                            <div class=\"counter-title\">CHF G\u00c9N\u00c9R\u00c9S, DANS LA POCHE DE NOS CLIENTS.<\/div>\r\n                                        <\/div>\r\n                                        <div class=\"counter-image\"><img decoding=\"async\" class=\"lazyload\" data-src=\"http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/08\/Webp.net-resizeimage-1.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/08\/Webp.net-resizeimage-1.jpg\" alt=\"\"><\/noscript>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                        <!--Right Column-->\r\n                        <div class=\"right-col col-xl-4 col-lg-12 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                <div class=\"form-box wow fadeInRight\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                    <!-- loading form via plugin -->\r\n                                                                            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/32554#wpcf7-f8-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"default-form\">\n\t<h4>PRISE DE CONTACT<span>.<\/span>\n\t<\/h4>\n\t<div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre nom*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adresse e-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"T\u00e9l\u00e9phone\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-service\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"your-service\"><option value=\"Service concern\u00e9\">Service concern\u00e9<\/option><option value=\"- Plusieurs services concern\u00e9s -\">- Plusieurs services concern\u00e9s -<\/option><option value=\"Sites web \/ Apps\">Sites web \/ Apps<\/option><option value=\"Publicit\u00e9 \/ Promotion \/ LinkedIn\">Publicit\u00e9 \/ Promotion \/ LinkedIn<\/option><option value=\"Design \/ Vid\u00e9o \/ Image de marque\">Design \/ Vid\u00e9o \/ Image de marque<\/option><option value=\"Influenceurs \/ Presse \/ TV\">Influenceurs \/ Presse \/ TV<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<p><button class=\"theme-btn btn-style-one\" type=\"submit\"><i class=\"btn-curve\"><\/i><span class=\"btn-title\">ENVOYER LA DEMANDE<\/span><\/button>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6Le39kQcAAAAAGYsphW3g7JTSOMu4UVjMWCIxjju\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe class=\"lazyload\" data-src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6Le39kQcAAAAAGYsphW3g7JTSOMu4UVjMWCIxjju\"  frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"114\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n\r\n        \r\n        \r\n\r\n        \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e73f67 elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-linoor-contact-form\" data-id=\"2e73f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n            <!--Get Quote Section-->\r\n            <section class=\"get-quote-section\">\r\n                <div class=\"auto-container\">\r\n                    <div class=\"row clearfix no-gutters\">\r\n                        <!--Left Column-->\r\n                        <div class=\"left-col col-xl-8 col-lg-12 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                <div class=\"featured-block clearfix\">\r\n                                    <div class=\"image\"><img decoding=\"async\" class=\"lazyload\" data-src=\"https:\/\/numeractive.ch\/wp-content\/uploads\/2024\/08\/pexels-olly-3771807-scaled.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/pexels-olly-3771807-scaled.jpg?ssl=1\" alt=\"\"><\/noscript><\/div>\r\n                                    <h4>TOP LEADER : D\u00e9veloppez votre pr\u00e9sence en ligne !\n<\/h4>\r\n                                    <div class=\"text\"><p>En tant que leader dans votre domaine, votre image en ligne est cruciale.<\/p>\n\n<p>Notre service d'accompagnement Top Leader est sp\u00e9cialement con\u00e7u pour les directeurs, les chefs d\u2019agence, les responsables et les CEO qui cherchent \u00e0 renforcer leur influence et leur impact sur le digital.<\/p>\n\n<p>\nNotre \u00e9quipe d\u00e9di\u00e9e travaille en \u00e9troite collaboration avec vous pour \u00e9laborer une strat\u00e9gie sur mesure, align\u00e9e sur votre vision et vos valeurs. Nous mettons \u00e0 profit notre expertise en marketing digital pour fa\u00e7onner votre image en ligne de mani\u00e8re authentique et percutante. <\/p>\n<p><b>Votre pr\u00e9sence en ligne aide \u00e0 am\u00e9liorer votre image personnelle et celle de votre entreprise !<b><\/p><\/div>\r\n                                <\/div>\r\n                                <div class=\"counter\">\r\n                                    <div class=\"counter-inner clearfix\">\r\n                                        <div class=\"counter-text\">\r\n                                            <div class=\"count-box\"><span class=\"count-text\" data-stop=\"86\" data-speed=\"2500\">0<\/span><\/div>\r\n                                            <div class=\"counter-title\">% de leaders actifs sur LinkedIn l'affirment<\/div>\r\n                                        <\/div>\r\n                                        <div class=\"counter-image\"><img decoding=\"async\" class=\"lazyload\" data-src=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"\"><noscript><img decoding=\"async\" src=\"\" alt=\"\"><\/noscript>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                        <!--Right Column-->\r\n                        <div class=\"right-col col-xl-4 col-lg-12 col-md-12 col-sm-12\">\r\n                            <div class=\"inner\">\r\n                                <div class=\"form-box wow fadeInRight\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                    <!-- loading form via plugin -->\r\n                                                                            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/32554#wpcf7-f8-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"default-form\">\n\t<h4>PRISE DE CONTACT<span>.<\/span>\n\t<\/h4>\n\t<div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre nom*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adresse e-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"T\u00e9l\u00e9phone\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"field-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-service\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"your-service\"><option value=\"Service concern\u00e9\">Service concern\u00e9<\/option><option value=\"- Plusieurs services concern\u00e9s -\">- Plusieurs services concern\u00e9s -<\/option><option value=\"Sites web \/ Apps\">Sites web \/ Apps<\/option><option value=\"Publicit\u00e9 \/ Promotion \/ LinkedIn\">Publicit\u00e9 \/ Promotion \/ LinkedIn<\/option><option value=\"Design \/ Vid\u00e9o \/ Image de marque\">Design \/ Vid\u00e9o \/ Image de marque<\/option><option value=\"Influenceurs \/ Presse \/ TV\">Influenceurs \/ Presse \/ TV<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-group\">\n\t\t\t<p><button class=\"theme-btn btn-style-one\" type=\"submit\"><i class=\"btn-curve\"><\/i><span class=\"btn-title\">ENVOYER LA DEMANDE<\/span><\/button>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6Le39kQcAAAAAGYsphW3g7JTSOMu4UVjMWCIxjju\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe class=\"lazyload\" data-src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6Le39kQcAAAAAGYsphW3g7JTSOMu4UVjMWCIxjju\"  frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"230\"\/><script>\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                                                                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n\r\n        \r\n        \r\n\r\n        \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b104ff8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b104ff8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce239de\" data-id=\"ce239de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df969fa elementor-widget elementor-widget-linoor-call-to-action\" data-id=\"df969fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        \r\n            <!-- Features Section -->\r\n            <section class=\"features-section jarallax\" data-jarallax data-speed=\"0.3\" data-imgPosition=\"50% -100%\">\r\n                <img decoding=\"async\" data-src=\"http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC07796-scaled.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"jarallax-img lazyload\" alt=\"\"><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC07796-scaled.jpg\" class=\"jarallax-img\" alt=\"\"><\/noscript>\r\n                <div class=\"auto-container\">\r\n                    <div class=\"content-box\">\r\n                        <h2>GRANDISSONS ENSEMBLE<span>.<\/span><\/h2>\r\n                        <div class=\"features clearfix\">\r\n                                                            <div class=\"feature-block\">\r\n                                    <div class=\"inner\">\r\n                                                                                <div class=\"icon-box\"><span class=\"flaticon-idea fas\"><\/span><\/div>\r\n                                        <h6>VOTRE R\u00c9USSITE,<BR>NOTRE SUCC\u00c8S<\/h6>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            <div class=\"feature-block\">\r\n                                    <div class=\"inner\">\r\n                                                                                <div class=\"icon-box\"><span class=\"flaticon-worldwide fas\"><\/span><\/div>\r\n                                        <h6>NOTORI\u00c9T\u00c9 LOCALE<BR \/>OU INTERNATIONALE<\/h6>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            <div class=\"feature-block\">\r\n                                    <div class=\"inner\">\r\n                                                                                <div class=\"icon-box\"><span class=\"flaticon-clock fas\"><\/span><\/div>\r\n                                        <h6>Agilit\u00e9 et<br>adaptation<\/h6>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                    <\/div>\r\n                        <div class=\"link-box\">\r\n                            <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/tous-les-services\/\">\r\n                                <i class=\"btn-curve\"><\/i>\r\n                                <span class=\"btn-title\">D\u00c9COUVREZ TOUS NOS SERVICES<\/span>\r\n                            <\/a>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n            <!-- End Funfacts Section -->\r\n\r\n        \r\n        \r\n        \r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fca3c27 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fca3c27\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf34854\" data-id=\"bf34854\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbc649f elementor-widget elementor-widget-linoor-sponsors\" data-id=\"bbc649f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-sponsors.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n                    <!--Sponsors Section-->\r\n            <section class=\"sponsors-section-two\">\r\n                <div class=\"auto-container\">\r\n                    <!--Sponsors Carousel-->\r\n                    <div class=\"row clearfix\">\r\n                        <div class=\"title-col col-xl-5 col-lg-12 col-md-12\">\r\n                            <div class=\"sec-title wow fadeInLeft\" data-wow-delay=\"0ms\" data-wow-duration=\"1500ms\">\r\n                                <h2>ILS NOUS FONT CONFIANCE<span class=\"dot\">.<\/span><\/h2>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class=\"logo-col col-xl-7 col-lg-12 col-md-12\">\r\n                            <div class=\"row clearfix\">\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/www.allergan.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"Allergan an AbbVie Company\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"Allergan an AbbVie Company\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/Allergan-an-AbbVie-Company-Logo-1-002.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/vaudoise.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo_Vaudoise_Assurances.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/swisslife-select.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/SLS_Logo.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/SLS_Logo.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/evok.com\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=18%2C5&amp;ssl=1 18w\" width=\"150\" height=\"48\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"48\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=150%2C48&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Logo.svg_.png.webp?resize=18%2C5&amp;ssl=1 18w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/4-b.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/08\/Capture-decran-2024-08-28-095141.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/forum-arc.ch\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/cropped-logo-head-menu-1-1920x486-1-1.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/logosansfond.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/new.swissmovie.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=138%2C70&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?w=138&amp;ssl=1 138w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=18%2C9&amp;ssl=1 18w\" width=\"138\" height=\"70\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"logo_swissmovie\"  sizes=\"(max-width: 138px) 100vw, 138px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"70\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=138%2C70&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"logo_swissmovie\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?w=138&amp;ssl=1 138w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/logo_swissmovie.png?resize=18%2C9&amp;ssl=1 18w\" sizes=\"(max-width: 138px) 100vw, 138px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/etudeferraz.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"etude_ferraz_logo\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"etude_ferraz_logo\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/12\/etude_ferraz_logo.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/de-blasio.opel.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/www.arom.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger-1.png?resize=150%2C80&amp;ssl=1\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2021\/07\/telecharger-1.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                                                    <div class=\"logo-block col-xl-4 col-lg-3 col-md-4 col-sm-6 col-xs-12\">\r\n                                        <div class=\"image-box\"><a href=\"https:\/\/lspartners.ch\/\" target=\"_blank\" rel=\"noopener\">\r\n                                                <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=18%2C9&amp;ssl=1 18w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" width=\"150\" height=\"80\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80 lazyload\" alt=\"LS Partners\"  sizes=\"(max-width: 150px) 100vw, 150px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"80\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1\" class=\"attachment-linoor_brand_logo_150X80 size-linoor_brand_logo_150X80\" alt=\"LS Partners\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=18%2C9&amp;ssl=1 18w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=2&amp;resize=150%2C80&amp;ssl=1 300w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2022\/05\/ls-partners-e1653532452873.png?zoom=3&amp;resize=150%2C80&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\"><\/noscript>                                            <\/a><\/div>\r\n                                    <\/div>\r\n\r\n                                \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                <\/div>\r\n            <\/section>\r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa62026 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fa62026\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2e4202\" data-id=\"b2e4202\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ce604e elementor-widget elementor-widget-linoor-call-to-action\" data-id=\"2ce604e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        \r\n        \r\n            <!-- Fluid Section -->\r\n            <section class=\"fluid-section\">\r\n                <div class=\"outer-container\">\r\n                    <div class=\"row clearfix\">\r\n                                                                                                        <div class=\"column col-lg-6 col-md-12 col-sm-12\">\r\n                                <div class=\"inner\">\r\n                                    <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC08045-scaled.jpg);\">\r\n                                    <\/div>\r\n                                    <div class=\"content-box\">\r\n                                        <h3>DEVANCEZ VOS CONCURRENTS ET CONSTRUISEZ VOTRE FUTUR<\/h3>\r\n                                        <div class=\"link-box\">\r\n                                            <a class=\"theme-btn btn-style-one\" href=\"https:\/\/numeractive.ch\/tous-les-services\/\">\r\n                                                <i class=\"btn-curve\"><\/i>\r\n                                                <span class=\"btn-title\">NOS SERVICES<\/span>\r\n                                            <\/a>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                                                                            <div class=\"column col-lg-6 col-md-12 col-sm-12\">\r\n                                <div class=\"inner\">\r\n                                    <div class=\"image-layer\" style=\"background-image: url(http:\/\/numeractive.ch\/wp-content\/uploads\/2021\/12\/DSC08039-scaled.jpg);\">\r\n                                    <\/div>\r\n                                    <div class=\"content-box\">\r\n                                        <h3>Nos mots-d'ordre:\nNotori\u00e9t\u00e9, cr\u00e9dibilit\u00e9 et succ\u00e8s<\/h3>\r\n                                        <div class=\"link-box\">\r\n                                            <a class=\"theme-btn btn-style-two\" href=\"https:\/\/numeractive.ch\/entrez-dans-lere-numeractive\/\">\r\n                                                <i class=\"btn-curve\"><\/i>\r\n                                                <span class=\"btn-title\">D\u00e9couvrez l&#039;\u00c8re NUMERACTIVE<\/span>\r\n                                            <\/a>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                                        <\/div>\r\n                <\/div>\r\n            <\/section>\r\n\r\n        \r\n        \r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88aa0f8 elementor-widget elementor-widget-linoor-blog\" data-id=\"88aa0f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n            <!-- News Section -->\r\n            <section class=\"news-section\">\r\n                <div class=\"auto-container\">\r\n                                            <div class=\"sec-title centered\">\r\n                            <h2>NOS DERNIERS ARTICLES<span class=\"dot\">.<\/span><\/h2>\r\n                        <\/div>\r\n                    \r\n                    <div class=\"row clearfix\">\r\n                                                                            <!--News Block-->\r\n                            <div class=\"news-block col-lg-4 col-md-6 col-sm-12\">\r\n                                <div class=\"inner-box\">\r\n                                    <div class=\"image-box\">\r\n                                        <a href=\"https:\/\/numeractive.ch\/it\/le-sfide-per-una-strategia-video-di-successo\/\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?resize=370%2C254&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" width=\"370\" height=\"254\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image lazyload\" alt=\"Les d\u00e9fis \u00e0 relever pour une strat\u00e9gie vid\u00e9o r\u00e9ussie\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"254\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?resize=370%2C254&amp;ssl=1\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image\" alt=\"Les d\u00e9fis \u00e0 relever pour une strat\u00e9gie vid\u00e9o r\u00e9ussie\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/11\/Les-defis-a-relever-pour-une-strategie-video-reussie.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript>                                        <\/a>\r\n                                    <\/div>\r\n                                    <div class=\"lower-box\">\r\n                                        <div class=\"post-meta\">\r\n                                            <ul class=\"clearfix m-0 list-unstyled\">\r\n                                                <li><span class=\"far fa-clock\"><\/span> 05 Dic<\/li>\r\n                                                                                                    <li><span class=\"byline\"><span class=\"far fa-user-circle\"><\/span> <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/numeractive.ch\/it\/author\/florianbourqui\/\">florianbourqui<\/a><\/span><\/span><\/li>\r\n                                                                                                                                                    <li><span class=\"comments-link\"><span class=\"far fa-comments\"><\/span><a href=\"https:\/\/numeractive.ch\/it\/le-sfide-per-una-strategia-video-di-successo\/#respond\">Leave a Comment<span class=\"screen-reader-text\"> on Les d\u00e9fis \u00e0 relever pour une strat\u00e9gie vid\u00e9o r\u00e9ussie<\/span><\/a><\/span><\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                        <h5><a href=\"https:\/\/numeractive.ch\/it\/le-sfide-per-una-strategia-video-di-successo\/\">Les d\u00e9fis \u00e0 relever pour une strat\u00e9gie vid\u00e9o r\u00e9ussie<\/a><\/h5>\r\n                                                                                    <div class=\"text\">\r\n                                                Table des Mati\u00e8res Introduction Pourquoi la vid\u00e9o est incontournable aujourd\u2019hui                                            <\/div>\r\n                                                                                <div class=\"link-box\"><a class=\"theme-btn\" href=\"https:\/\/numeractive.ch\/it\/le-sfide-per-una-strategia-video-di-successo\/\"><span class=\"flaticon-next-1\"><\/span><\/a><\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <!--News Block-->\r\n                            <div class=\"news-block col-lg-4 col-md-6 col-sm-12\">\r\n                                <div class=\"inner-box\">\r\n                                    <div class=\"image-box\">\r\n                                        <a href=\"https:\/\/numeractive.ch\/it\/tiktok-e-instagram-il-nuovo-google-per-i-giovani\/\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?resize=370%2C254&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" width=\"370\" height=\"254\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image lazyload\" alt=\"TikTok et Instagram : Le nouveau Google des jeunes ?\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"254\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?resize=370%2C254&amp;ssl=1\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image\" alt=\"TikTok et Instagram : Le nouveau Google des jeunes ?\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/10\/1.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript>                                        <\/a>\r\n                                    <\/div>\r\n                                    <div class=\"lower-box\">\r\n                                        <div class=\"post-meta\">\r\n                                            <ul class=\"clearfix m-0 list-unstyled\">\r\n                                                <li><span class=\"far fa-clock\"><\/span> 25 Ott<\/li>\r\n                                                                                                    <li><span class=\"byline\"><span class=\"far fa-user-circle\"><\/span> <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/numeractive.ch\/it\/author\/florianbourqui\/\">florianbourqui<\/a><\/span><\/span><\/li>\r\n                                                                                                                                                    <li><span class=\"comments-link\"><span class=\"far fa-comments\"><\/span><a href=\"https:\/\/numeractive.ch\/it\/tiktok-e-instagram-il-nuovo-google-per-i-giovani\/#respond\">Leave a Comment<span class=\"screen-reader-text\"> on TikTok et Instagram : le nouveau Google des jeunes ?<\/span><\/a><\/span><\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                        <h5><a href=\"https:\/\/numeractive.ch\/it\/tiktok-e-instagram-il-nuovo-google-per-i-giovani\/\">TikTok et Instagram : le nouveau Google des jeunes ?<\/a><\/h5>\r\n                                                                                    <div class=\"text\">\r\n                                                Table des Mati\u00e8res Introduction TikTok et Instagram : des moteurs                                            <\/div>\r\n                                                                                <div class=\"link-box\"><a class=\"theme-btn\" href=\"https:\/\/numeractive.ch\/it\/tiktok-e-instagram-il-nuovo-google-per-i-giovani\/\"><span class=\"flaticon-next-1\"><\/span><\/a><\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                    <!--News Block-->\r\n                            <div class=\"news-block col-lg-4 col-md-6 col-sm-12\">\r\n                                <div class=\"inner-box\">\r\n                                    <div class=\"image-box\">\r\n                                        <a href=\"https:\/\/numeractive.ch\/it\/limportanza-della-seo-locale-per-le-imprese-locali\/\">\r\n                                            <img loading=\"lazy\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?resize=370%2C254&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" width=\"370\" height=\"254\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image lazyload\" alt=\"L&#039;importance du SEO local pour les commerces de proximit\u00e9\"  sizes=\"(max-width: 370px) 100vw, 370px\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"254\" src=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?resize=370%2C254&amp;ssl=1\" class=\"attachment-linoor_blog_370X254 size-linoor_blog_370X254 wp-post-image\" alt=\"L&#039;importance du SEO local pour les commerces de proximit\u00e9\" srcset=\"https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?resize=370%2C254&amp;ssl=1 370w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?zoom=2&amp;resize=370%2C254&amp;ssl=1 740w, https:\/\/i0.wp.com\/numeractive.ch\/wp-content\/uploads\/2024\/09\/1.png?zoom=3&amp;resize=370%2C254&amp;ssl=1 1110w\" sizes=\"(max-width: 370px) 100vw, 370px\"><\/noscript>                                        <\/a>\r\n                                    <\/div>\r\n                                    <div class=\"lower-box\">\r\n                                        <div class=\"post-meta\">\r\n                                            <ul class=\"clearfix m-0 list-unstyled\">\r\n                                                <li><span class=\"far fa-clock\"><\/span> 24 Set<\/li>\r\n                                                                                                    <li><span class=\"byline\"><span class=\"far fa-user-circle\"><\/span> <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/numeractive.ch\/it\/author\/florianbourqui\/\">florianbourqui<\/a><\/span><\/span><\/li>\r\n                                                                                                                                                    <li><span class=\"comments-link\"><span class=\"far fa-comments\"><\/span><a href=\"https:\/\/numeractive.ch\/it\/limportanza-della-seo-locale-per-le-imprese-locali\/#respond\">Leave a Comment<span class=\"screen-reader-text\"> on L&rsquo;importance du SEO local pour les commerces de proximit\u00e9<\/span><\/a><\/span><\/li>\r\n                                                                                            <\/ul>\r\n                                        <\/div>\r\n                                        <h5><a href=\"https:\/\/numeractive.ch\/it\/limportanza-della-seo-locale-per-le-imprese-locali\/\">L&rsquo;importance du SEO local pour les commerces de proximit\u00e9<\/a><\/h5>\r\n                                                                                    <div class=\"text\">\r\n                                                Table des Mati\u00e8res Introduction Pourquoi le SEO local est devenu                                            <\/div>\r\n                                                                                <div class=\"link-box\"><a class=\"theme-btn\" href=\"https:\/\/numeractive.ch\/it\/limportanza-della-seo-locale-per-le-imprese-locali\/\"><span class=\"flaticon-next-1\"><\/span><\/a><\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                                                                                            <\/div>\r\n                <\/div>\r\n            <\/section>\r\n\r\n        \r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fini les t\u00e9l\u00e9phones inutiles, place \u00e0 l&rsquo;automatisation LinkedIn! Automatisez votre prospection avec LinkedIn D\u00e9marchez des entreprises Communiquez efficacement avec votre audience Laissez faire les pros des r\u00e9seaux! Nous g\u00e9rons vos r\u00e9seaux sociaux R\u00e9v\u00e9lez votre leadership en ligne ! Top Leader : D\u00e9veloppez votre pr\u00e9sence en ligne Personal Branding Les meilleures techniques pour vous rendre c\u00e9l\u00e8bre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-32554","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/pages\/32554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/comments?post=32554"}],"version-history":[{"count":33,"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/pages\/32554\/revisions"}],"predecessor-version":[{"id":32594,"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/pages\/32554\/revisions\/32594"}],"wp:attachment":[{"href":"https:\/\/numeractive.ch\/it\/wp-json\/wp\/v2\/media?parent=32554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}